{"id":3073,"date":"2019-02-25T15:31:28","date_gmt":"2019-02-25T15:31:28","guid":{"rendered":"https:\/\/www.spg.com.tn\/?page_id=3073"},"modified":"2022-01-19T16:01:25","modified_gmt":"2022-01-19T16:01:25","slug":"services-cloud","status":"publish","type":"page","link":"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/","title":{"rendered":"Cloud Services"},"content":{"rendered":"<section class=\"cover height-60 imagebg text-center\" data-overlay=\"0\" >\n\t\t\t    <div class=\"background-image-holder\">\n\t\t\t        <img loading=\"lazy\" decoding=\"async\" width=\"1351\" height=\"556\" src=\"https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2019\/08\/Services-Cloud.jpg?fit=1351%2C556&amp;ssl=1\" class=\"attachment-full size-full\" alt=\"Cloud\" srcset=\"https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2019\/08\/Services-Cloud.jpg?w=1351&amp;ssl=1 1351w, https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2019\/08\/Services-Cloud.jpg?resize=300%2C123&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2019\/08\/Services-Cloud.jpg?resize=768%2C316&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2019\/08\/Services-Cloud.jpg?resize=1024%2C421&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/>\n\t\t\t    <\/div>\n\t\t\t    <div class=\"container pos-vertical-center\">\n\t\t\t        <div class=\"row\">\n\t\t\t            <div class=\"col-sm-12\"><h1 style=\"font-size: 40px;color: #ffffff;line-height: 40px;text-align: center;font-family:Lato;font-weight:700;font-style:normal\" class=\"vc_custom_heading\" >Cloud Services<\/h1><\/div>\n\t\t\t        <\/div><!--end of row-->\n\t\t\t    <\/div><!--end of container-->\n\t\t\t    \n\t\t\t<\/section>\n\t\t<div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container col-sm-12 vc_hidden-sm vc_hidden-xs\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t\t<section class=\"imageblock switchable switchable--switch regular-background feature-large space--sm\">\n\t\t\t    <div class=\"imageblock__content col-md-6 col-sm-4 pos-right\">\n\t\t\t        <div class=\"background-image-holder\">\n\t\t\t            <img loading=\"lazy\" decoding=\"async\" width=\"676\" height=\"676\" src=\"https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2019\/08\/CLOUD.jpg?fit=676%2C676&amp;ssl=1\" class=\"attachment-full size-full\" alt=\"Cloud\" srcset=\"https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2019\/08\/CLOUD.jpg?w=676&amp;ssl=1 676w, https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2019\/08\/CLOUD.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2019\/08\/CLOUD.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2019\/08\/CLOUD.jpg?resize=60%2C60&amp;ssl=1 60w\" sizes=\"auto, (max-width: 676px) 100vw, 676px\" \/>\n\t\t\t        <\/div>\n\t\t\t    <\/div>\n\t\t\t    <div class=\"container\">\n\t\t\t        <div class=\"row\">\n\t\t\t            <div class=\"col-md-5 col-sm-7\">\n\t\t\t                \n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\">Cloud computing services have revolutionized access to and use of information technology in businesses of all sizes and in all industries.<br \/>\nThese services have acted as a true catalyst for digital transformation and have pushed companies to rethink their existing systems.<br \/>\nToday, thanks to a wide range of Cloud Computing services, we have been able to accompany this change and provide answers to most of the IT needs of our customers and partners.<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"500\"><span class='pum-trigger  popmake-3295' data-do-default=''><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2022\/01\/telechargement-1.png?resize=300%2C150&#038;ssl=1\" alt=\"\" class=\"alignleft size-full wp-image-25921\" width=\"300\" height=\"150\"\/><\/span><\/td>\n<td width=\"500\"><span class='pum-trigger  popmake-3274' data-do-default=''><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2022\/01\/MS-Azure_logo_stacked_c-gray_rgb.png?resize=300%2C150&#038;ssl=1\" alt=\"\" class=\"alignleft size-full wp-image-25921\" width=\"300\" height=\"150\"\/><\/span><\/td>\n<td width=\"500\"><span class='pum-trigger  popmake-3297' data-do-default=''><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2022\/01\/Microsoft-365-01.jpg?resize=300%2C150&#038;ssl=1\" alt=\"\" class=\"alignleft size-full wp-image-25921\" width=\"300\" height=\"150\"\/><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<span class='pum-trigger  popmake-48692' data-do-default=''><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-25921\" src=\"https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2022\/01\/dynamics-01.jpg?resize=300%2C150&#038;ssl=1\" alt=\"\" width=\"300\" height=\"150\"\/><\/span>\n\n\t\t<\/div>\n\t<\/div>\n\n\t\t\t            <\/div>\n\t\t\t        <\/div><!--end of row-->\n\t\t\t    <\/div><!--end of container-->\n\t\t\t<\/section>\n\t\t<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container col-sm-12 vc_hidden-lg vc_hidden-md\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1642176578759\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\">Cloud computing services have revolutionized access to and use of information technology in businesses of all sizes and in all industries.<br \/>\nThese services have acted as a true catalyst for digital transformation and have pushed companies to rethink their existing systems.<br \/>\nToday, thanks to a wide range of Cloud Computing services, we have been able to accompany this change and provide answers to most of the IT needs of our customers and partners.<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"500\"><span class='pum-trigger  popmake-3295' data-do-default=''><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2019\/02\/microsoft-cloud-1.png?resize=300%2C150&#038;ssl=1\" alt=\"\" class=\"alignleft size-full wp-image-25921\" width=\"300\" height=\"150\"\/><\/span><\/td>\n<td width=\"500\"><span class='pum-trigger  popmake-3274' data-do-default=''><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2019\/02\/microsoft-azure-1.png?resize=300%2C150&#038;ssl=1\" alt=\"\" class=\"alignleft size-full wp-image-25921\" width=\"300\" height=\"150\"\/><\/span><\/td>\n<td width=\"500\"><span class='pum-trigger  popmake-3297' data-do-default=''><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2022\/01\/microsoft-office-01.jpg?resize=300%2C150&#038;ssl=1\" alt=\"\" class=\"alignleft size-full wp-image-25921\" width=\"300\" height=\"150\"\/><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>","protected":false},"excerpt":{"rendered":"SERVICES CLOUD Les services de Cloud Computing ont r\u00e9volutionn\u00e9 l\u2019acc\u00e8s et l\u2019utilisation des technologies de l\u2019information au sein des entreprises de toutes...","protected":false},"author":29,"featured_media":0,"parent":3028,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-3073","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"SERVICES CLOUD Les services de Cloud Computing ont r\u00e9volutionn\u00e9 l\u2019acc\u00e8s et l\u2019utilisation des technologies de l\u2019information au sein des entreprises de toutes tailles et dans tous les secteurs d\u2019activit\u00e9s. Ces services ont jou\u00e9 le r\u00f4le d\u2019un v\u00e9ritable catalyseur de transformation num\u00e9rique et ont pouss\u00e9 les entreprises \u00e0 repenser leurs syst\u00e8mes existants. Aujourd\u2019hui, gr\u00e2ce \u00e0 une\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SPG - Grossiste Informatique \u00e0 Valeur ajout\u00e9e\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Services Cloud - SPG\" \/>\n\t\t<meta property=\"og:description\" content=\"SERVICES CLOUD Les services de Cloud Computing ont r\u00e9volutionn\u00e9 l\u2019acc\u00e8s et l\u2019utilisation des technologies de l\u2019information au sein des entreprises de toutes tailles et dans tous les secteurs d\u2019activit\u00e9s. Ces services ont jou\u00e9 le r\u00f4le d\u2019un v\u00e9ritable catalyseur de transformation num\u00e9rique et ont pouss\u00e9 les entreprises \u00e0 repenser leurs syst\u00e8mes existants. Aujourd\u2019hui, gr\u00e2ce \u00e0 une\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-02-25T15:31:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-01-19T16:01:25+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Services Cloud - SPG\" \/>\n\t\t<meta name=\"twitter:description\" content=\"SERVICES CLOUD Les services de Cloud Computing ont r\u00e9volutionn\u00e9 l\u2019acc\u00e8s et l\u2019utilisation des technologies de l\u2019information au sein des entreprises de toutes tailles et dans tous les secteurs d\u2019activit\u00e9s. Ces services ont jou\u00e9 le r\u00f4le d\u2019un v\u00e9ritable catalyseur de transformation num\u00e9rique et ont pouss\u00e9 les entreprises \u00e0 repenser leurs syst\u00e8mes existants. Aujourd\u2019hui, gr\u00e2ce \u00e0 une\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/categories\\\/services-cloud\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.spg.com.tn\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/categories\\\/#listItem\",\"name\":\"Cat\\u00e9gories\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/categories\\\/#listItem\",\"position\":2,\"name\":\"Cat\\u00e9gories\",\"item\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/categories\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/categories\\\/services-cloud\\\/#listItem\",\"name\":\"Services Cloud\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/categories\\\/services-cloud\\\/#listItem\",\"position\":3,\"name\":\"Services Cloud\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/categories\\\/#listItem\",\"name\":\"Cat\\u00e9gories\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/#organization\",\"name\":\"SPG\",\"description\":\"Grossiste Informatique \\u00e0 Valeur ajout\\u00e9e\",\"url\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/categories\\\/services-cloud\\\/#webpage\",\"url\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/categories\\\/services-cloud\\\/\",\"name\":\"Services Cloud - SPG\",\"description\":\"SERVICES CLOUD Les services de Cloud Computing ont r\\u00e9volutionn\\u00e9 l\\u2019acc\\u00e8s et l\\u2019utilisation des technologies de l\\u2019information au sein des entreprises de toutes tailles et dans tous les secteurs d\\u2019activit\\u00e9s. Ces services ont jou\\u00e9 le r\\u00f4le d\\u2019un v\\u00e9ritable catalyseur de transformation num\\u00e9rique et ont pouss\\u00e9 les entreprises \\u00e0 repenser leurs syst\\u00e8mes existants. Aujourd\\u2019hui, gr\\u00e2ce \\u00e0 une\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/categories\\\/services-cloud\\\/#breadcrumblist\"},\"datePublished\":\"2019-02-25T15:31:28+00:00\",\"dateModified\":\"2022-01-19T16:01:25+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/\",\"name\":\"SPG\",\"description\":\"Grossiste Informatique \\u00e0 Valeur ajout\\u00e9e\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Services Cloud - SPG","description":"SERVICES CLOUD Les services de Cloud Computing ont r\u00e9volutionn\u00e9 l\u2019acc\u00e8s et l\u2019utilisation des technologies de l\u2019information au sein des entreprises de toutes tailles et dans tous les secteurs d\u2019activit\u00e9s. Ces services ont jou\u00e9 le r\u00f4le d\u2019un v\u00e9ritable catalyseur de transformation num\u00e9rique et ont pouss\u00e9 les entreprises \u00e0 repenser leurs syst\u00e8mes existants. Aujourd\u2019hui, gr\u00e2ce \u00e0 une","canonical_url":"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.spg.com.tn\/en#listItem","position":1,"name":"Home","item":"https:\/\/www.spg.com.tn\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.spg.com.tn\/en\/categories\/#listItem","name":"Cat\u00e9gories"}},{"@type":"ListItem","@id":"https:\/\/www.spg.com.tn\/en\/categories\/#listItem","position":2,"name":"Cat\u00e9gories","item":"https:\/\/www.spg.com.tn\/en\/categories\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/#listItem","name":"Services Cloud"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.spg.com.tn\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/#listItem","position":3,"name":"Services Cloud","previousItem":{"@type":"ListItem","@id":"https:\/\/www.spg.com.tn\/en\/categories\/#listItem","name":"Cat\u00e9gories"}}]},{"@type":"Organization","@id":"https:\/\/www.spg.com.tn\/en\/#organization","name":"SPG","description":"Grossiste Informatique \u00e0 Valeur ajout\u00e9e","url":"https:\/\/www.spg.com.tn\/en\/"},{"@type":"WebPage","@id":"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/#webpage","url":"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/","name":"Services Cloud - SPG","description":"SERVICES CLOUD Les services de Cloud Computing ont r\u00e9volutionn\u00e9 l\u2019acc\u00e8s et l\u2019utilisation des technologies de l\u2019information au sein des entreprises de toutes tailles et dans tous les secteurs d\u2019activit\u00e9s. Ces services ont jou\u00e9 le r\u00f4le d\u2019un v\u00e9ritable catalyseur de transformation num\u00e9rique et ont pouss\u00e9 les entreprises \u00e0 repenser leurs syst\u00e8mes existants. Aujourd\u2019hui, gr\u00e2ce \u00e0 une","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.spg.com.tn\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/#breadcrumblist"},"datePublished":"2019-02-25T15:31:28+00:00","dateModified":"2022-01-19T16:01:25+00:00"},{"@type":"WebSite","@id":"https:\/\/www.spg.com.tn\/en\/#website","url":"https:\/\/www.spg.com.tn\/en\/","name":"SPG","description":"Grossiste Informatique \u00e0 Valeur ajout\u00e9e","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.spg.com.tn\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"SPG - Grossiste Informatique \u00e0 Valeur ajout\u00e9e","og:type":"article","og:title":"Services Cloud - SPG","og:description":"SERVICES CLOUD Les services de Cloud Computing ont r\u00e9volutionn\u00e9 l\u2019acc\u00e8s et l\u2019utilisation des technologies de l\u2019information au sein des entreprises de toutes tailles et dans tous les secteurs d\u2019activit\u00e9s. Ces services ont jou\u00e9 le r\u00f4le d\u2019un v\u00e9ritable catalyseur de transformation num\u00e9rique et ont pouss\u00e9 les entreprises \u00e0 repenser leurs syst\u00e8mes existants. Aujourd\u2019hui, gr\u00e2ce \u00e0 une","og:url":"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/","article:published_time":"2019-02-25T15:31:28+00:00","article:modified_time":"2022-01-19T16:01:25+00:00","twitter:card":"summary_large_image","twitter:title":"Services Cloud - SPG","twitter:description":"SERVICES CLOUD Les services de Cloud Computing ont r\u00e9volutionn\u00e9 l\u2019acc\u00e8s et l\u2019utilisation des technologies de l\u2019information au sein des entreprises de toutes tailles et dans tous les secteurs d\u2019activit\u00e9s. Ces services ont jou\u00e9 le r\u00f4le d\u2019un v\u00e9ritable catalyseur de transformation num\u00e9rique et ont pouss\u00e9 les entreprises \u00e0 repenser leurs syst\u00e8mes existants. Aujourd\u2019hui, gr\u00e2ce \u00e0 une"},"aioseo_meta_data":{"post_id":"3073","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-07-28 10:24:23","updated":"2025-06-17 10:11:31","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.spg.com.tn\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.spg.com.tn\/en\/categories\/\" title=\"Cat\u00e9gories\">Cat\u00e9gories<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tServices Cloud\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.spg.com.tn\/en"},{"label":"Cat\u00e9gories","link":"https:\/\/www.spg.com.tn\/en\/categories\/"},{"label":"Services Cloud","link":"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Services Cloud - SPG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Services Cloud - SPG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/\" \/>\n<meta property=\"og:site_name\" content=\"SPG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SPG.Software.Productivity.Group\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-19T16:01:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.spg.com.tn\/wp-content\/uploads\/2022\/01\/telechargement-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/categories\\\/services-cloud\\\/\",\"url\":\"https:\\\/\\\/www.spg.com.tn\\\/categories\\\/services-cloud\\\/\",\"name\":\"Services Cloud - SPG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/categories\\\/services-cloud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/categories\\\/services-cloud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.spg.com.tn\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/telechargement-1.png\",\"datePublished\":\"2019-02-25T15:31:28+00:00\",\"dateModified\":\"2022-01-19T16:01:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/categories\\\/services-cloud\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.spg.com.tn\\\/categories\\\/services-cloud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/categories\\\/services-cloud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.spg.com.tn\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/telechargement-1.png\",\"contentUrl\":\"https:\\\/\\\/www.spg.com.tn\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/telechargement-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/categories\\\/services-cloud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.spg.com.tn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e9gories\",\"item\":\"https:\\\/\\\/www.spg.com.tn\\\/categories\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Services Cloud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/#website\",\"url\":\"https:\\\/\\\/www.spg.com.tn\\\/\",\"name\":\"SPG\",\"description\":\"Grossiste Informatique \u00e0 Valeur ajout\u00e9e\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/#organization\"},\"alternateName\":\"SPG distributeur des solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.spg.com.tn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/#organization\",\"name\":\"SPG\",\"url\":\"https:\\\/\\\/www.spg.com.tn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.spg.com.tn\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Logo-SPG-new.png?fit=300%2C133&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.spg.com.tn\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Logo-SPG-new.png?fit=300%2C133&ssl=1\",\"width\":300,\"height\":133,\"caption\":\"SPG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.spg.com.tn\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SPG.Software.Productivity.Group\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/software-productivity-group-spg\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Services Cloud - SPG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/","og_locale":"en_US","og_type":"article","og_title":"Services Cloud - SPG","og_url":"https:\/\/www.spg.com.tn\/en\/categories\/services-cloud\/","og_site_name":"SPG","article_publisher":"https:\/\/www.facebook.com\/SPG.Software.Productivity.Group\/","article_modified_time":"2022-01-19T16:01:25+00:00","og_image":[{"url":"https:\/\/www.spg.com.tn\/wp-content\/uploads\/2022\/01\/telechargement-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.spg.com.tn\/categories\/services-cloud\/","url":"https:\/\/www.spg.com.tn\/categories\/services-cloud\/","name":"Services Cloud - SPG","isPartOf":{"@id":"https:\/\/www.spg.com.tn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.spg.com.tn\/categories\/services-cloud\/#primaryimage"},"image":{"@id":"https:\/\/www.spg.com.tn\/categories\/services-cloud\/#primaryimage"},"thumbnailUrl":"https:\/\/www.spg.com.tn\/wp-content\/uploads\/2022\/01\/telechargement-1.png","datePublished":"2019-02-25T15:31:28+00:00","dateModified":"2022-01-19T16:01:25+00:00","breadcrumb":{"@id":"https:\/\/www.spg.com.tn\/categories\/services-cloud\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.spg.com.tn\/categories\/services-cloud\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.spg.com.tn\/categories\/services-cloud\/#primaryimage","url":"https:\/\/www.spg.com.tn\/wp-content\/uploads\/2022\/01\/telechargement-1.png","contentUrl":"https:\/\/www.spg.com.tn\/wp-content\/uploads\/2022\/01\/telechargement-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.spg.com.tn\/categories\/services-cloud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.spg.com.tn\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e9gories","item":"https:\/\/www.spg.com.tn\/categories\/"},{"@type":"ListItem","position":3,"name":"Services Cloud"}]},{"@type":"WebSite","@id":"https:\/\/www.spg.com.tn\/#website","url":"https:\/\/www.spg.com.tn\/","name":"SPG","description":"Grossiste Informatique \u00e0 Valeur ajout\u00e9e","publisher":{"@id":"https:\/\/www.spg.com.tn\/#organization"},"alternateName":"SPG distributeur des solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.spg.com.tn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.spg.com.tn\/#organization","name":"SPG","url":"https:\/\/www.spg.com.tn\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.spg.com.tn\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2023\/07\/Logo-SPG-new.png?fit=300%2C133&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.spg.com.tn\/wp-content\/uploads\/2023\/07\/Logo-SPG-new.png?fit=300%2C133&ssl=1","width":300,"height":133,"caption":"SPG"},"image":{"@id":"https:\/\/www.spg.com.tn\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SPG.Software.Productivity.Group\/","https:\/\/www.linkedin.com\/company\/software-productivity-group-spg\/"]}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PaWB6B-Nz","jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.spg.com.tn\/en\/wp-json\/wp\/v2\/pages\/3073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spg.com.tn\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.spg.com.tn\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.spg.com.tn\/en\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spg.com.tn\/en\/wp-json\/wp\/v2\/comments?post=3073"}],"version-history":[{"count":8,"href":"https:\/\/www.spg.com.tn\/en\/wp-json\/wp\/v2\/pages\/3073\/revisions"}],"predecessor-version":[{"id":48602,"href":"https:\/\/www.spg.com.tn\/en\/wp-json\/wp\/v2\/pages\/3073\/revisions\/48602"}],"up":[{"embeddable":true,"href":"https:\/\/www.spg.com.tn\/en\/wp-json\/wp\/v2\/pages\/3028"}],"wp:attachment":[{"href":"https:\/\/www.spg.com.tn\/en\/wp-json\/wp\/v2\/media?parent=3073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}